{"id":13104,"date":"2012-11-08T03:44:50","date_gmt":"2012-11-08T03:44:50","guid":{"rendered":"http:\/\/bme2.flywheelsites.com\/es\/blog\/como-crear-sus-propias-infografias\/"},"modified":"2024-09-16T15:26:36","modified_gmt":"2024-09-16T15:26:36","slug":"como-crear-sus-propias-infografias","status":"publish","type":"post","link":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/","title":{"rendered":"como-crear-sus-propias-infografias"},"content":{"rendered":"<p>A principios de este a\u00f1o, se dijo que el marketing visual ser\u00eda la pr\u00f3xima sensaci\u00f3n &#8211; y se ha convertido en eso. Hemos visto la calidad de im\u00e1genes que lo acompa\u00f1an cada vez m\u00e1s de forma competitiva entre las publicaciones. Hemos visto el aumento sin precedentes de Pinterest, una plataforma puramente basada en im\u00e1genes diferenci\u00e1ndose de otras redes sociales y ahora la tercera m\u00e1s grande a pesar de los cientos que han venido antes de \u00e9l. Incluso hemos visto la atenci\u00f3n hacia emparejamientos tipogr\u00e1ficos, donde los diferentes tipos de fuentes complementarias est\u00e1n emparejadas juntos para hacer que el texto destaque a\u00fan m\u00e1s, hasta el punto de que el texto es ahora una forma de arte.<\/p>\n<p>Y luego est\u00e1n las <a href=\"http:\/\/domclaxton.tumblr.com\/post\/16453247892\/300-million-infographics-and-growing\" class=\"external\" rel=\"nofollow noopener noreferrer\" target=\"_blank\">infograf\u00edas<\/a>, dependiendo de c\u00f3mo se refiera a ellas. Las infograf\u00edas se han convertido en la \u00fanica manera de comunicar realmente la informaci\u00f3n. Es un modo creativo y llamativo para atraer a los lectores en una gran cantidad de datos sin que sus ojos se pongan vidriosos minutos despu\u00e9s. Por el contrario, las infograf\u00edas llegan a los lectores curiosos y hacen que quieran leer m\u00e1s, aprender m\u00e1s y compartir m\u00e1s (sobre todo con el cambio social hacia saber m\u00e1s, pero es un tema que vamos a guardar para otro d\u00eda).<\/p>\n<p>Entonces, \u00bfqu\u00e9 son exactamente las infograf\u00edas utilizadas? Tal vez usted est\u00e1 pensando que su empresa no tiene realmente mucha informaci\u00f3n para compartir, y mucho menos informaci\u00f3n que la gente quiere saber. Aunque aqu\u00ed est\u00e1 la cosa: su infograf\u00eda podr\u00eda estar en cualquier cosa que a la gente le provoque curiosidad.<\/p>\n<p>Rhode Island esta basada en Caster Communications, un experto de la compa\u00f1\u00eda PR, hizo una publicaci\u00f3n muy divertida y creativa durante el verano titulado &#8220;\u00bfCu\u00e1ndo es demasiado caliente para su perro?&#8221; No ten\u00eda nada que ver con relaciones p\u00fablicas, pero era una manera divertida de incorporar su perrito, que a menudo se encuentran constantemente vigilando las puertas &#8211; ya que est\u00e1n durmiendo en las almohadillas de felpa. Incluso sin el factor de relaciones p\u00fablicas, se ha incorporado la cultura de la oficina y su amor por los perros, proporcionando informaci\u00f3n \u00fatil a otros y oportuna. Apuesto que cualquier amante de los perros comparten esto.<\/p>\n<p>Cuando se trata de infograf\u00edas, en realidad se est\u00e1 limitado \u00fanicamente por su imaginaci\u00f3n.<\/p>\n<h4>Creaci\u00f3n De Una Infograf\u00eda<\/h4>\n<div>\n<p>Hay media docena de herramientas gratuitas y accesibles por ah\u00ed para ayudarle a crear su infograf\u00eda, comenzando con:<\/p>\n<ol>\n<li><a href=\"http:\/\/creat.visual.ly\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external\">Visual.ly<\/a> \u2013 Solo tiene que registrarse y conectarse a sus cuentas sociales. Visual.ly hace que sea f\u00e1cil saber c\u00f3mo dar formato a su infograf\u00eda por lo que permite disparar a un objetivo final. \u00bfQu\u00e9 tipo de historia est\u00e1 buscando usted para comunicarse? Esto determinar\u00e1 su estructura gr\u00e1fica. Mientras est\u00e9 all\u00ed, eche un vistazo a todas las im\u00e1genes de otros grandes e insp\u00edrese. Si usted est\u00e1 buscando algo simple y muy bien dise\u00f1ado, pero no es tan desglosado en su enfoque, luego puede probar <a href=\"http:\/\/www.piktochart.com\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external\">Piktochart<\/a>.<\/li>\n<li><a href=\"http:\/\/easel.ly\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external\">Easel.ly<\/a> \u2013 Hace que la creaci\u00f3n gr\u00e1fica sea simple y la mejor opci\u00f3n para los principiantes con poca experiencia y pocos conocimientos de dise\u00f1o.<\/li>\n<li>\u00a0<a href=\"http:\/\/www.dipity.com\/\" class=\"external\" rel=\"nofollow noopener noreferrer\" target=\"_blank\">Dipity<\/a> &#8211; Lo mejor para la creaci\u00f3n de l\u00edneas de tiempo.<\/li>\n<li><a href=\"http:\/\/infogr.am\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external\">Infogr.am<\/a> \u2013 Si usted tiene un sitio de datos pesados, esto es para usted. Infogr.am le permite importar datos directamente desde su sitio web.<\/li>\n<li><a href=\"http:\/\/venngage.com\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external\">Venngage<\/a> \u2013 Es perfecto para la creaci\u00f3n de diagramas de Venn. Como punto positivo extra, Venngage tambi\u00e9n le permite rastrear a los usuarios d\u00e1ndole rendimiento a la infograf\u00eda.<\/li>\n<\/ol>\n<p>Si usted no tiene el tiempo, puede contratar a un dise\u00f1ador gr\u00e1fico &#8211; a pesar de que le puede costar un ojo de la cara. Tambi\u00e9n puede ir a la ruta m\u00e1s barata mediante la contrataci\u00f3n de una escuela secundaria o un talentoso estudiante universitario con conocimientos t\u00e9cnicos. S\u00f3lo aseg\u00farese de darles informaci\u00f3n respecto a la direcci\u00f3n y detalles de dise\u00f1o.<\/p>\n<\/div>\n<h4>El Dise\u00f1o De Su Infograf\u00eda&lt;\/h4<\/h4>\n<div>\n<p>A pesar de que su infograf\u00eda puede estar sobre cualquier cosa, tiene que hacerlo atractivo a la vista, si al menos quiere que los lectores hagan clic una vez sobre su infograf\u00eda y la quieran compartir.<\/p>\n<p>Use de 3 a 5 cinco colores con una <a>rueda de color<\/a> para determinar los tonos complementarios. Si usted no tiene idea de por d\u00f3nde empezar, comience con los colores de la marca y as\u00ed inyectarse en unos pocos acentos grises o tonos neutros. El siguiente paso es el emparejamiento de la fuente. Comience con el tipo de letra que utiliza para su logotipo y el sitio Web. Para obtener una mezcla m\u00e1s creativa, agregue en uno m\u00e1s.<\/p>\n<\/div>\n<p>Los profesionales de <a href=\"https:\/\/www.benchmarkemail.com\/es\/\">email marketing<\/a> de Benchmark, lo manti\u00e9nen informado con las noticias y consejos m\u00e1s relevantes para su empresa, siguiendo las mejores pr\u00e1cticas del <a href=\"https:\/\/www.benchmarkemail.com\/es\/email-marketing\/\">marketing por email<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A principios de este a\u00f1o, se dijo que el marketing visual ser\u00eda la pr\u00f3xima sensaci\u00f3n &#8211; y se ha convertido en eso. Hemos visto la calidad de im\u00e1genes que lo acompa\u00f1an cada vez m\u00e1s de forma competitiva entre las publicaciones. Hemos visto el aumento sin precedentes de Pinterest, una plataforma puramente basada en im\u00e1genes diferenci\u00e1ndose&hellip;<\/p>\n","protected":false},"author":309,"featured_media":13105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3948],"tags":[],"class_list":["post-13104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>como-crear-sus-propias-infografias - Benchmark Email<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"como-crear-sus-propias-infografias - Benchmark Email\" \/>\n<meta property=\"og:description\" content=\"A principios de este a\u00f1o, se dijo que el marketing visual ser\u00eda la pr\u00f3xima sensaci\u00f3n &#8211; y se ha convertido en eso. Hemos visto la calidad de im\u00e1genes que lo acompa\u00f1an cada vez m\u00e1s de forma competitiva entre las publicaciones. Hemos visto el aumento sin precedentes de Pinterest, una plataforma puramente basada en im\u00e1genes diferenci\u00e1ndose&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/\" \/>\n<meta property=\"og:site_name\" content=\"Benchmark Email - Herramienta de Email Marketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/benchmarkemailes\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-08T03:44:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T15:26:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Shireen Qudosi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@benchmarkesp\" \/>\n<meta name=\"twitter:site\" content=\"@benchmarkesp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shireen Qudosi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/\"},\"author\":{\"name\":\"Shireen Qudosi\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#\\\/schema\\\/person\\\/e4ef80bf829cd482f3bf6c28d6091cf4\"},\"headline\":\"como-crear-sus-propias-infografias\",\"datePublished\":\"2012-11-08T03:44:50+00:00\",\"dateModified\":\"2024-09-16T15:26:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/\"},\"wordCount\":858,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/02\\\/Modest-Budget-Large-6.png\",\"articleSection\":[\"Otros Contenidos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/\",\"url\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/\",\"name\":\"como-crear-sus-propias-infografias - Benchmark Email\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/02\\\/Modest-Budget-Large-6.png\",\"datePublished\":\"2012-11-08T03:44:50+00:00\",\"dateModified\":\"2024-09-16T15:26:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/02\\\/Modest-Budget-Large-6.png\",\"contentUrl\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/02\\\/Modest-Budget-Large-6.png\",\"width\":660,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/blog\\\/como-crear-sus-propias-infografias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"como-crear-sus-propias-infografias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/\",\"name\":\"Benchmark Email - Herramienta de Email Marketing\",\"description\":\"Dise\u00f1a, env\u00eda, mide y optimiza tus campa\u00f1as de email y comun\u00edcate con tus clientes a trav\u00e9s del correo electr\u00f3nico.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#organization\",\"name\":\"Benchmark Email\",\"url\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/benchmark-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/benchmark-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Benchmark Email\"},\"image\":{\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/benchmarkemailes\",\"https:\\\/\\\/x.com\\\/benchmarkesp\",\"https:\\\/\\\/twitter.com\\\/benchmarkesp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BenchmarkEmailESP\",\"https:\\\/\\\/www.tiktok.com\\\/@benchmarkespanol\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.benchmarkemail.com\\\/es\\\/#\\\/schema\\\/person\\\/e4ef80bf829cd482f3bf6c28d6091cf4\",\"name\":\"Shireen Qudosi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g\",\"caption\":\"Shireen Qudosi\"},\"description\":\"Shireen Qudosi is Benchmark Email's Online Marketing Specialist and Small Business Advocate. An Orange County based writer, Shireen specializes in online marketing and public relations. She has written for over 75 publications and has launched nine successful new media campaigns to date. Her work has been featured in the New York Times, Denver Post, the Oklahoman and Green Air Radio, among others.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"como-crear-sus-propias-infografias - Benchmark Email","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/","og_locale":"en_US","og_type":"article","og_title":"como-crear-sus-propias-infografias - Benchmark Email","og_description":"A principios de este a\u00f1o, se dijo que el marketing visual ser\u00eda la pr\u00f3xima sensaci\u00f3n &#8211; y se ha convertido en eso. Hemos visto la calidad de im\u00e1genes que lo acompa\u00f1an cada vez m\u00e1s de forma competitiva entre las publicaciones. Hemos visto el aumento sin precedentes de Pinterest, una plataforma puramente basada en im\u00e1genes diferenci\u00e1ndose&hellip;","og_url":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/","og_site_name":"Benchmark Email - Herramienta de Email Marketing","article_publisher":"https:\/\/www.facebook.com\/benchmarkemailes","article_published_time":"2012-11-08T03:44:50+00:00","article_modified_time":"2024-09-16T15:26:36+00:00","og_image":[{"width":660,"height":438,"url":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png","type":"image\/png"}],"author":"Shireen Qudosi","twitter_card":"summary_large_image","twitter_creator":"@benchmarkesp","twitter_site":"@benchmarkesp","twitter_misc":{"Written by":"Shireen Qudosi","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#article","isPartOf":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/"},"author":{"name":"Shireen Qudosi","@id":"https:\/\/www.benchmarkemail.com\/es\/#\/schema\/person\/e4ef80bf829cd482f3bf6c28d6091cf4"},"headline":"como-crear-sus-propias-infografias","datePublished":"2012-11-08T03:44:50+00:00","dateModified":"2024-09-16T15:26:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/"},"wordCount":858,"commentCount":0,"publisher":{"@id":"https:\/\/www.benchmarkemail.com\/es\/#organization"},"image":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png","articleSection":["Otros Contenidos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/","url":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/","name":"como-crear-sus-propias-infografias - Benchmark Email","isPartOf":{"@id":"https:\/\/www.benchmarkemail.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#primaryimage"},"image":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png","datePublished":"2012-11-08T03:44:50+00:00","dateModified":"2024-09-16T15:26:36+00:00","breadcrumb":{"@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#primaryimage","url":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png","contentUrl":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2020\/02\/Modest-Budget-Large-6.png","width":660,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/www.benchmarkemail.com\/es\/blog\/como-crear-sus-propias-infografias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.benchmarkemail.com\/es\/"},{"@type":"ListItem","position":2,"name":"como-crear-sus-propias-infografias"}]},{"@type":"WebSite","@id":"https:\/\/www.benchmarkemail.com\/es\/#website","url":"https:\/\/www.benchmarkemail.com\/es\/","name":"Benchmark Email - Herramienta de Email Marketing","description":"Dise\u00f1a, env\u00eda, mide y optimiza tus campa\u00f1as de email y comun\u00edcate con tus clientes a trav\u00e9s del correo electr\u00f3nico.","publisher":{"@id":"https:\/\/www.benchmarkemail.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.benchmarkemail.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.benchmarkemail.com\/es\/#organization","name":"Benchmark Email","url":"https:\/\/www.benchmarkemail.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.benchmarkemail.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/benchmark-logo.svg","contentUrl":"https:\/\/www.benchmarkemail.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/benchmark-logo.svg","width":1,"height":1,"caption":"Benchmark Email"},"image":{"@id":"https:\/\/www.benchmarkemail.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/benchmarkemailes","https:\/\/x.com\/benchmarkesp","https:\/\/twitter.com\/benchmarkesp","https:\/\/www.youtube.com\/user\/BenchmarkEmailESP","https:\/\/www.tiktok.com\/@benchmarkespanol"]},{"@type":"Person","@id":"https:\/\/www.benchmarkemail.com\/es\/#\/schema\/person\/e4ef80bf829cd482f3bf6c28d6091cf4","name":"Shireen Qudosi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/558ab8e78927bc045d7ebb8bc5239ccb256bfc5555a92639a69b9e0869a03814?s=96&d=mm&r=g","caption":"Shireen Qudosi"},"description":"Shireen Qudosi is Benchmark Email's Online Marketing Specialist and Small Business Advocate. An Orange County based writer, Shireen specializes in online marketing and public relations. She has written for over 75 publications and has launched nine successful new media campaigns to date. Her work has been featured in the New York Times, Denver Post, the Oklahoman and Green Air Radio, among others."}]}},"_links":{"self":[{"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/posts\/13104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/users\/309"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/comments?post=13104"}],"version-history":[{"count":0,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/posts\/13104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/media\/13105"}],"wp:attachment":[{"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/media?parent=13104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/categories?post=13104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benchmarkemail.com\/es\/wp-json\/wp\/v2\/tags?post=13104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}